{"id":24,"count":14,"description":"","link":"https:\/\/osakan.net\/saas\/cashless\/square\/","name":"Square","slug":"square","taxonomy":"category","parent":4,"meta":[],"_links":{"self":[{"href":"https:\/\/osakan.net\/saas\/wp-json\/wp\/v2\/categories\/24","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osakan.net\/saas\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/osakan.net\/saas\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/osakan.net\/saas\/wp-json\/wp\/v2\/categories\/4"}],"wp:post_type":[{"href":"https:\/\/osakan.net\/saas\/wp-json\/wp\/v2\/posts?categories=24"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}